{"id":999849,"date":"2024-03-20T08:30:44","date_gmt":"2024-03-20T11:30:44","guid":{"rendered":"http:\/\/souzaokawa.provisorio.ws\/provisional-measure-1202-2023\/"},"modified":"2024-08-07T14:25:31","modified_gmt":"2024-08-07T17:25:31","slug":"provisional-measure-1202-2023","status":"publish","type":"post","link":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/","title":{"rendered":"Provisional Measure 1,202\/2023"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"999849\" class=\"elementor elementor-999849 elementor-993339\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ba41da8 e-flex e-con-boxed e-con e-parent\" data-id=\"3ba41da8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53f3e61 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"53f3e61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Closing the legislative changes proposed by the Federal Government in 2023 to reduce the primary deficit in 2024, on December 29th, the Provisional Measure No. 1,202 was published, establishing the reoneration of payroll, the return of taxation on the events sector, and the creation of limits for tax offsetting of credits resulting from judicial decisions.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-879af85 e-flex e-con-boxed e-con e-parent\" data-id=\"879af85\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-c9c090f elementor-align-left elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"c9c090f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/medida-provisoria-1202-2023.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Provisional Measure 1,202\/2023<\/p>\n","protected":false},"author":1,"featured_media":999407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[418],"tags":[596,445],"area":[534],"class_list":["post-999849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tax","tag-1475423-en","tag-law","area-tax"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Provisional Measure 1,202\/2023 - SouzaOkawa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provisional Measure 1,202\/2023 - SouzaOkawa\" \/>\n<meta property=\"og:description\" content=\"Provisional Measure 1,202\/2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"SouzaOkawa\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T11:30:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T17:25:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminfan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminfan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/\"},\"author\":{\"name\":\"adminfan\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#\/schema\/person\/1ac1821b221c40f31776342549ae4fa6\"},\"headline\":\"Provisional Measure 1,202\/2023\",\"datePublished\":\"2024-03-20T11:30:44+00:00\",\"dateModified\":\"2024-08-07T17:25:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/\"},\"wordCount\":55,\"publisher\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg\",\"keywords\":[\"1475423\",\"law\"],\"articleSection\":[\"Tax\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/\",\"url\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/\",\"name\":\"Provisional Measure 1,202\/2023 - SouzaOkawa\",\"isPartOf\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg\",\"datePublished\":\"2024-03-20T11:30:44+00:00\",\"dateModified\":\"2024-08-07T17:25:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#primaryimage\",\"url\":\"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg\",\"contentUrl\":\"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg\",\"width\":400,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/souzaokawa.com.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provisional Measure 1,202\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#website\",\"url\":\"https:\/\/souzaokawa.com.br\/en\/\",\"name\":\"SouzaOkawa\",\"description\":\"Site Jur\u00eddico do escrit\u00f3rio SouzaOkawa\",\"publisher\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/souzaokawa.com.br\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#organization\",\"name\":\"SouzaOkawa\",\"url\":\"https:\/\/souzaokawa.com.br\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/04\/souza-okawa-logo.svg\",\"contentUrl\":\"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/04\/souza-okawa-logo.svg\",\"width\":1984,\"height\":223,\"caption\":\"SouzaOkawa\"},\"image\":{\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#\/schema\/person\/1ac1821b221c40f31776342549ae4fa6\",\"name\":\"adminfan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/souzaokawa.com.br\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/souzaokawa.com.br\/wp-content\/litespeed\/avatar\/75e8d162e2aa44841df5c594dd0d46c0.jpg?ver=1788274521\",\"contentUrl\":\"https:\/\/souzaokawa.com.br\/wp-content\/litespeed\/avatar\/75e8d162e2aa44841df5c594dd0d46c0.jpg?ver=1788274521\",\"caption\":\"adminfan\"},\"sameAs\":[\"https:\/\/souzaokawa.com.br\"],\"url\":\"https:\/\/souzaokawa.com.br\/en\/author\/adminfan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provisional Measure 1,202\/2023 - SouzaOkawa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/","og_locale":"en_US","og_type":"article","og_title":"Provisional Measure 1,202\/2023 - SouzaOkawa","og_description":"Provisional Measure 1,202\/2023","og_url":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/","og_site_name":"SouzaOkawa","article_published_time":"2024-03-20T11:30:44+00:00","article_modified_time":"2024-08-07T17:25:31+00:00","og_image":[{"width":400,"height":480,"url":"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg","type":"image\/jpeg"}],"author":"adminfan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adminfan","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#article","isPartOf":{"@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/"},"author":{"name":"adminfan","@id":"https:\/\/souzaokawa.com.br\/en\/#\/schema\/person\/1ac1821b221c40f31776342549ae4fa6"},"headline":"Provisional Measure 1,202\/2023","datePublished":"2024-03-20T11:30:44+00:00","dateModified":"2024-08-07T17:25:31+00:00","mainEntityOfPage":{"@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/"},"wordCount":55,"publisher":{"@id":"https:\/\/souzaokawa.com.br\/en\/#organization"},"image":{"@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg","keywords":["1475423","law"],"articleSection":["Tax"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/","url":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/","name":"Provisional Measure 1,202\/2023 - SouzaOkawa","isPartOf":{"@id":"https:\/\/souzaokawa.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#primaryimage"},"image":{"@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg","datePublished":"2024-03-20T11:30:44+00:00","dateModified":"2024-08-07T17:25:31+00:00","breadcrumb":{"@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#primaryimage","url":"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg","contentUrl":"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/03\/card-informativos-fundo-branco.jpg","width":400,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/souzaokawa.com.br\/en\/provisional-measure-1202-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/souzaokawa.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Provisional Measure 1,202\/2023"}]},{"@type":"WebSite","@id":"https:\/\/souzaokawa.com.br\/en\/#website","url":"https:\/\/souzaokawa.com.br\/en\/","name":"SouzaOkawa","description":"Site Jur\u00eddico do escrit\u00f3rio SouzaOkawa","publisher":{"@id":"https:\/\/souzaokawa.com.br\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/souzaokawa.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/souzaokawa.com.br\/en\/#organization","name":"SouzaOkawa","url":"https:\/\/souzaokawa.com.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/souzaokawa.com.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/04\/souza-okawa-logo.svg","contentUrl":"https:\/\/souzaokawa.com.br\/wp-content\/uploads\/2024\/04\/souza-okawa-logo.svg","width":1984,"height":223,"caption":"SouzaOkawa"},"image":{"@id":"https:\/\/souzaokawa.com.br\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/souzaokawa.com.br\/en\/#\/schema\/person\/1ac1821b221c40f31776342549ae4fa6","name":"adminfan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/souzaokawa.com.br\/en\/#\/schema\/person\/image\/","url":"https:\/\/souzaokawa.com.br\/wp-content\/litespeed\/avatar\/75e8d162e2aa44841df5c594dd0d46c0.jpg?ver=1788274521","contentUrl":"https:\/\/souzaokawa.com.br\/wp-content\/litespeed\/avatar\/75e8d162e2aa44841df5c594dd0d46c0.jpg?ver=1788274521","caption":"adminfan"},"sameAs":["https:\/\/souzaokawa.com.br"],"url":"https:\/\/souzaokawa.com.br\/en\/author\/adminfan\/"}]}},"_links":{"self":[{"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/posts\/999849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/comments?post=999849"}],"version-history":[{"count":0,"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/posts\/999849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/media\/999407"}],"wp:attachment":[{"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/media?parent=999849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/categories?post=999849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/tags?post=999849"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/souzaokawa.com.br\/en\/wp-json\/wp\/v2\/area?post=999849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}